{"id":4217,"date":"2022-07-07T08:34:52","date_gmt":"2022-07-07T00:34:52","guid":{"rendered":"https:\/\/luxpowertek.com\/?p=4217"},"modified":"2022-07-07T09:20:28","modified_gmt":"2022-07-07T01:20:28","slug":"convertisseur-c-c-a-chaines-multiples","status":"publish","type":"post","link":"https:\/\/luxpowertek.com\/fr\/blog\/convertisseur-c-c-a-chaines-multiples\/","title":{"rendered":"LuxpowerTek lance un convertisseur DC-DC multi-cha\u00eene"},"content":{"rendered":"<p>Certains pays commencent \u00e0 limiter la puissance photovolta\u00efque connect\u00e9e au r\u00e9seau et le prix des panneaux solaires diminue. Les onduleurs de stockage d'\u00e9nergie deviennent donc de plus en plus populaires. C'est pourquoi nous avons lanc\u00e9 le premier convertisseur DC\/DC 100K de Chine pour transformer le syst\u00e8me ON GRID existant en syst\u00e8me de stockage d'\u00e9nergie. Ce convertisseur CC\/CC peut non seulement augmenter la capacit\u00e9 des panneaux solaires existants, mais aussi... Augmenter le taux d'auto-utilisation du syst\u00e8me solaire existant.<\/p>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Cet appareil pr\u00e9sente les caract\u00e9ristiques suivantes :<\/span><b><\/b><\/h3><\/div>\n<ul>\n<li>Ce convertisseur CC\/CC poss\u00e8de une entr\u00e9e PV, une sortie PV et une interface avec la batterie. Il fonctionne en stockant l'\u00e9nergie solaire exc\u00e9dentaire dans la batterie du c\u00f4t\u00e9 CC et en simulant la sortie du panneau solaire vers l'onduleur PV. Et comme la courbe de simulation de la sortie est conforme aux caract\u00e9ristiques des panneaux solaires, notre appareil peut s'adapter \u00e0 n'importe quelle marque d'onduleur photovolta\u00efque.<\/li>\n<\/ul>\n<div class=\"row align-middle\"  id=\"row-1694902916\">\n\n\t<div id=\"col-1705514435\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1260045796\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"619\" src=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/17.PV-inverter-1030x625.webp\" class=\"attachment-large size-large\" alt=\"Onduleur PV\" srcset=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/17.PV-inverter-1030x625.webp 1030w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/17.PV-inverter-300x182.webp 300w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/17.PV-inverter-768x466.webp 768w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/17.PV-inverter-800x485.webp 800w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/17.PV-inverter.webp 1348w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1260045796 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<ul>\n<li>Le convertisseur DC-DC peut contr\u00f4ler l'entr\u00e9e PV, ce qui signifie qu'il peut \u00e9galement charger la batterie lorsqu'il n'y a pas de r\u00e9seau.<\/li>\n<li>Ce convertisseur permet de d\u00e9finir la p\u00e9riode de priorit\u00e9 de charge<\/li>\n<li>Le convertisseur DC-DC a une plage de tension d'entr\u00e9e DC de 300-1000V et comprend 24 cha\u00eenes solaires d'entr\u00e9e et 12 cha\u00eenes de sortie.<\/li>\n<li>Le convertisseur CC\/CC est compatible avec les batteries plomb-acide et lithium-ion dont la tension est comprise entre 300 et 700 VCC.<\/li>\n<li>Il a un rendement de 97,9% et un rendement europ\u00e9en de 97,5%.<\/li>\n<li>Il b\u00e9n\u00e9ficie d'une protection IP65 et peut donc \u00eatre install\u00e9 \u00e0 l'int\u00e9rieur ou \u00e0 l'ext\u00e9rieur.<\/li>\n<li>Les convertisseurs c.c. \u00e0 c.c. b\u00e9n\u00e9ficient d'une garantie de cinq ans. La dur\u00e9e de vie des convertisseurs c.c.-c.c. peut atteindre plus de 15 ans dans un environnement \u00e0 25 degr\u00e9s.<\/li>\n<li>Le convertisseur DC DC int\u00e8gre une collecte intelligente de donn\u00e9es pour l'assistance \u00e0 distance et propose des param\u00e8tres de compte flexibles pour les utilisateurs de type multi-niveaux.<\/li>\n<\/ul>\n<div class=\"row align-middle\"  id=\"row-1261791550\">\n\n\t<div id=\"col-2090061554\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1008735374\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"494\" src=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/16.solar-power-generation-1030x499.webp\" class=\"attachment-large size-large\" alt=\"la production d&#039;\u00e9nergie solaire\" srcset=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/16.solar-power-generation-1030x499.webp 1030w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/16.solar-power-generation-300x145.webp 300w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/16.solar-power-generation-768x372.webp 768w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/16.solar-power-generation-800x387.webp 800w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/16.solar-power-generation.webp 1374w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1008735374 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>En tant que nouvelle orientation du stockage de l'\u00e9nergie, ce syst\u00e8me peut r\u00e9duire consid\u00e9rablement le temps de transformation des centrales solaires existantes. Les convertisseurs \u00e0 courant continu r\u00e9alisent la fonction de centrale \u00e9lectrique virtuelle (VPP), ce qui permet de programmer rapidement l'\u00e9nergie et de r\u00e9soudre le probl\u00e8me de l'instabilit\u00e9 de la production d'\u00e9nergie solaire. Voici quelques photos de l'installation :<\/p>\n<div class=\"row align-middle\"  id=\"row-391721755\">\n\n\t<div id=\"col-212387477\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_581519167\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"579\" src=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/15.converter-installation-pictures.webp\" class=\"attachment-large size-large\" alt=\"Photos de l&#039;installation de l&#039;onduleur\" srcset=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/15.converter-installation-pictures.webp 433w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/15.converter-installation-pictures-224x300.webp 224w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_581519167 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-465002404\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_774138379\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"438\" height=\"580\" src=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/14.installation-pictures.webp\" class=\"attachment-large size-large\" alt=\"photos d&#039;installation\" srcset=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/14.installation-pictures.webp 438w, https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/14.installation-pictures-227x300.webp 227w\" sizes=\"auto, (max-width: 438px) 100vw, 438px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_774138379 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Certains pays commencent \u00e0 limiter la puissance photovolta\u00efque connect\u00e9e au r\u00e9seau et le prix des panneaux solaires diminue. Les onduleurs de stockage d'\u00e9nergie deviennent donc de plus en plus populaires. C'est pourquoi nous avons lanc\u00e9 le premier convertisseur DC\/DC 100K de Chine pour transformer le syst\u00e8me ON GRID existant en syst\u00e8me de stockage d'\u00e9nergie. Ce convertisseur DC\/DC peut non seulement...<\/p>","protected":false},"author":7,"featured_media":4218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[16],"tags":[],"class_list":["post-4217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LuxpowerTek Launches the\u00a0First DC\/DC Converter\u00a0<\/title>\n<meta name=\"description\" content=\"The Multi-string DC-DC Converter is the commonly used alternative. The electrical variables are measured by means of a DC-DC converter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxpowertek.com\/fr\/blog\/convertisseur-c-c-a-chaines-multiples\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LuxpowerTek Launches the\u00a0First DC\/DC Converter\u00a0\" \/>\n<meta property=\"og:description\" content=\"The Multi-string DC-DC Converter is the commonly used alternative. The electrical variables are measured by means of a DC-DC converter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxpowertek.com\/fr\/blog\/convertisseur-c-c-a-chaines-multiples\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LUXPOWERTEK\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-07T00:34:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-07T01:20:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/13.-DC-DC-converter..webp\" \/>\n\t<meta property=\"og:image:width\" content=\"636\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"wenli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hx_admin\" \/>\n<meta name=\"twitter:site\" content=\"@luxpowertek\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"wenli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/\"},\"author\":{\"name\":\"wenli\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#\\\/schema\\\/person\\\/567b97b380797b915e1e23366a26008c\"},\"headline\":\"LuxpowerTek Launches Multi-string DC-DC Converter\",\"datePublished\":\"2022-07-07T00:34:52+00:00\",\"dateModified\":\"2022-07-07T01:20:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/\"},\"wordCount\":385,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxpowertek.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/13.-DC-DC-converter..webp\",\"articleSection\":[\"About Products\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/\",\"url\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/\",\"name\":\"LuxpowerTek Launches the\u00a0First DC\\\/DC Converter\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/luxpowertek.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/13.-DC-DC-converter..webp\",\"datePublished\":\"2022-07-07T00:34:52+00:00\",\"dateModified\":\"2022-07-07T01:20:28+00:00\",\"description\":\"The Multi-string DC-DC Converter is the commonly used alternative. The electrical variables are measured by means of a DC-DC converter.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/luxpowertek.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/13.-DC-DC-converter..webp\",\"contentUrl\":\"https:\\\/\\\/luxpowertek.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/13.-DC-DC-converter..webp\",\"width\":636,\"height\":476,\"caption\":\"DC-DC converter.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/blog\\\/multi-string-dc-dc-converter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/luxpowertek.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Products\",\"item\":\"https:\\\/\\\/luxpowertek.com\\\/zh\\\/blog\\\/\u7c7b\u522b\\\/\u65b0\u95fb\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LuxpowerTek Launches Multi-string DC-DC Converter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#website\",\"url\":\"https:\\\/\\\/luxpowertek.com\\\/\",\"name\":\"LuxpowerTek\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/luxpowertek.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#organization\",\"name\":\"LuxpowerTek\",\"url\":\"https:\\\/\\\/luxpowertek.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/luxpowertek.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Luxpower_logo_new.webp\",\"contentUrl\":\"https:\\\/\\\/luxpowertek.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Luxpower_logo_new.webp\",\"width\":1030,\"height\":186,\"caption\":\"LuxpowerTek\"},\"image\":{\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LUXPOWERTEK\",\"https:\\\/\\\/x.com\\\/luxpowertek\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCS2wAmubDmcI44I_xKGWLQg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/luxpowertek\\\/\",\"https:\\\/\\\/www.instagram.com\\\/luxpowertek?igsh=bWd0aXg3YWJzc3N0\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/luxpowertek.com\\\/#\\\/schema\\\/person\\\/567b97b380797b915e1e23366a26008c\",\"name\":\"wenli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab2b9f1e8f0a42ef69e043360f1d777438509036232c68ee91362357ced18944?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab2b9f1e8f0a42ef69e043360f1d777438509036232c68ee91362357ced18944?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab2b9f1e8f0a42ef69e043360f1d777438509036232c68ee91362357ced18944?s=96&d=mm&r=g\",\"caption\":\"wenli\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/hx_admin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LuxpowerTek lance le premier convertisseur DC\/DC\u00a0","description":"Le convertisseur DC-DC \u00e0 cha\u00eenes multiples est l'alternative couramment utilis\u00e9e. Les variables \u00e9lectriques sont mesur\u00e9es au moyen d'un convertisseur DC-DC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxpowertek.com\/fr\/blog\/convertisseur-c-c-a-chaines-multiples\/","og_locale":"fr_FR","og_type":"article","og_title":"LuxpowerTek Launches the\u00a0First DC\/DC Converter\u00a0","og_description":"The Multi-string DC-DC Converter is the commonly used alternative. The electrical variables are measured by means of a DC-DC converter.","og_url":"https:\/\/luxpowertek.com\/fr\/blog\/convertisseur-c-c-a-chaines-multiples\/","article_publisher":"https:\/\/www.facebook.com\/LUXPOWERTEK","article_published_time":"2022-07-07T00:34:52+00:00","article_modified_time":"2022-07-07T01:20:28+00:00","og_image":[{"width":636,"height":476,"url":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/13.-DC-DC-converter..webp","type":"image\/webp"}],"author":"wenli","twitter_card":"summary_large_image","twitter_creator":"@hx_admin","twitter_site":"@luxpowertek","twitter_misc":{"\u00c9crit par":"wenli","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#article","isPartOf":{"@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/"},"author":{"name":"wenli","@id":"https:\/\/luxpowertek.com\/#\/schema\/person\/567b97b380797b915e1e23366a26008c"},"headline":"LuxpowerTek Launches Multi-string DC-DC Converter","datePublished":"2022-07-07T00:34:52+00:00","dateModified":"2022-07-07T01:20:28+00:00","mainEntityOfPage":{"@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/"},"wordCount":385,"commentCount":0,"publisher":{"@id":"https:\/\/luxpowertek.com\/#organization"},"image":{"@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#primaryimage"},"thumbnailUrl":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/13.-DC-DC-converter..webp","articleSection":["About Products"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/","url":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/","name":"LuxpowerTek lance le premier convertisseur DC\/DC\u00a0","isPartOf":{"@id":"https:\/\/luxpowertek.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#primaryimage"},"image":{"@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#primaryimage"},"thumbnailUrl":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/13.-DC-DC-converter..webp","datePublished":"2022-07-07T00:34:52+00:00","dateModified":"2022-07-07T01:20:28+00:00","description":"Le convertisseur DC-DC \u00e0 cha\u00eenes multiples est l'alternative couramment utilis\u00e9e. Les variables \u00e9lectriques sont mesur\u00e9es au moyen d'un convertisseur DC-DC.","breadcrumb":{"@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#primaryimage","url":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/13.-DC-DC-converter..webp","contentUrl":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2022\/07\/13.-DC-DC-converter..webp","width":636,"height":476,"caption":"DC-DC converter."},{"@type":"BreadcrumbList","@id":"https:\/\/luxpowertek.com\/blog\/multi-string-dc-dc-converter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/luxpowertek.com\/"},{"@type":"ListItem","position":2,"name":"About Products","item":"https:\/\/luxpowertek.com\/zh\/blog\/\u7c7b\u522b\/\u65b0\u95fb\/"},{"@type":"ListItem","position":3,"name":"LuxpowerTek Launches Multi-string DC-DC Converter"}]},{"@type":"WebSite","@id":"https:\/\/luxpowertek.com\/#website","url":"https:\/\/luxpowertek.com\/","name":"LuxpowerTek","description":"","publisher":{"@id":"https:\/\/luxpowertek.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxpowertek.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/luxpowertek.com\/#organization","name":"LuxpowerTek","url":"https:\/\/luxpowertek.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/luxpowertek.com\/#\/schema\/logo\/image\/","url":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2024\/08\/Luxpower_logo_new.webp","contentUrl":"https:\/\/luxpowertek.com\/wp-content\/uploads\/2024\/08\/Luxpower_logo_new.webp","width":1030,"height":186,"caption":"LuxpowerTek"},"image":{"@id":"https:\/\/luxpowertek.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LUXPOWERTEK","https:\/\/x.com\/luxpowertek","https:\/\/www.youtube.com\/channel\/UCS2wAmubDmcI44I_xKGWLQg","https:\/\/www.linkedin.com\/company\/luxpowertek\/","https:\/\/www.instagram.com\/luxpowertek?igsh=bWd0aXg3YWJzc3N0"]},{"@type":"Person","@id":"https:\/\/luxpowertek.com\/#\/schema\/person\/567b97b380797b915e1e23366a26008c","name":"wenli","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ab2b9f1e8f0a42ef69e043360f1d777438509036232c68ee91362357ced18944?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab2b9f1e8f0a42ef69e043360f1d777438509036232c68ee91362357ced18944?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab2b9f1e8f0a42ef69e043360f1d777438509036232c68ee91362357ced18944?s=96&d=mm&r=g","caption":"wenli"},"sameAs":["https:\/\/x.com\/hx_admin"]}]}},"_links":{"self":[{"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/posts\/4217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/comments?post=4217"}],"version-history":[{"count":0,"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/posts\/4217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/media\/4218"}],"wp:attachment":[{"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/media?parent=4217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/categories?post=4217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/luxpowertek.com\/fr\/wp-json\/wp\/v2\/tags?post=4217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}